{"id":70,"count":1,"description":"","link":"https:\/\/designjeem.com\/fr\/portfolio-industry\/sports-fitness\/","name":"Sports &amp; Fitness","slug":"sports-fitness","taxonomy":"portfolio_industry","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sports &amp; Fitness Archives - designjeem.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/designjeem.com\/fr\/portfolio-industry\/sports-fitness\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sports &amp; Fitness Archives - designjeem.com\" \/>\n<meta property=\"og:url\" content=\"https:\/\/designjeem.com\/fr\/portfolio-industry\/sports-fitness\/\" \/>\n<meta property=\"og:site_name\" content=\"designjeem.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/designjeem.com\\\/portfolio-industry\\\/sports-fitness\\\/\",\"url\":\"https:\\\/\\\/designjeem.com\\\/portfolio-industry\\\/sports-fitness\\\/\",\"name\":\"Sports &amp; Fitness Archives - designjeem.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/designjeem.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/designjeem.com\\\/portfolio-industry\\\/sports-fitness\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/designjeem.com\\\/portfolio-industry\\\/sports-fitness\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/designjeem.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sports &amp; Fitness\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/designjeem.com\\\/#website\",\"url\":\"https:\\\/\\\/designjeem.com\\\/\",\"name\":\"designjeem.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/designjeem.com\\\/#\\\/schema\\\/person\\\/c24a3b7f2ae1c8ffddcb766a47c250d0\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/designjeem.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/designjeem.com\\\/#\\\/schema\\\/person\\\/c24a3b7f2ae1c8ffddcb766a47c250d0\",\"name\":\"Junaid Jamshaid\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/designjeem.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/cropped-Main-Logo.png\",\"url\":\"https:\\\/\\\/designjeem.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/cropped-Main-Logo.png\",\"contentUrl\":\"https:\\\/\\\/designjeem.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/cropped-Main-Logo.png\",\"width\":226,\"height\":226,\"caption\":\"Junaid Jamshaid\"},\"logo\":{\"@id\":\"https:\\\/\\\/designjeem.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/cropped-Main-Logo.png\"},\"sameAs\":[\"http:\\\/\\\/designjeem.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sports &amp; Fitness Archives - designjeem.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/designjeem.com\/fr\/portfolio-industry\/sports-fitness\/","og_locale":"fr_CA","og_type":"article","og_title":"Sports &amp; Fitness Archives - designjeem.com","og_url":"https:\/\/designjeem.com\/fr\/portfolio-industry\/sports-fitness\/","og_site_name":"designjeem.com","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/designjeem.com\/portfolio-industry\/sports-fitness\/","url":"https:\/\/designjeem.com\/portfolio-industry\/sports-fitness\/","name":"Sports &amp; Fitness Archives - designjeem.com","isPartOf":{"@id":"https:\/\/designjeem.com\/#website"},"breadcrumb":{"@id":"https:\/\/designjeem.com\/portfolio-industry\/sports-fitness\/#breadcrumb"},"inLanguage":"fr-CA"},{"@type":"BreadcrumbList","@id":"https:\/\/designjeem.com\/portfolio-industry\/sports-fitness\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/designjeem.com\/"},{"@type":"ListItem","position":2,"name":"Sports &amp; Fitness"}]},{"@type":"WebSite","@id":"https:\/\/designjeem.com\/#website","url":"https:\/\/designjeem.com\/","name":"designjeem.com","description":"","publisher":{"@id":"https:\/\/designjeem.com\/#\/schema\/person\/c24a3b7f2ae1c8ffddcb766a47c250d0"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/designjeem.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":["Person","Organization"],"@id":"https:\/\/designjeem.com\/#\/schema\/person\/c24a3b7f2ae1c8ffddcb766a47c250d0","name":"Junaid Jamshaid","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/designjeem.com\/wp-content\/uploads\/2026\/05\/cropped-Main-Logo.png","url":"https:\/\/designjeem.com\/wp-content\/uploads\/2026\/05\/cropped-Main-Logo.png","contentUrl":"https:\/\/designjeem.com\/wp-content\/uploads\/2026\/05\/cropped-Main-Logo.png","width":226,"height":226,"caption":"Junaid Jamshaid"},"logo":{"@id":"https:\/\/designjeem.com\/wp-content\/uploads\/2026\/05\/cropped-Main-Logo.png"},"sameAs":["http:\/\/designjeem.com"]}]}},"_links":{"self":[{"href":"https:\/\/designjeem.com\/fr\/wp-json\/wp\/v2\/portfolio_industry\/70","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/designjeem.com\/fr\/wp-json\/wp\/v2\/portfolio_industry"}],"about":[{"href":"https:\/\/designjeem.com\/fr\/wp-json\/wp\/v2\/taxonomies\/portfolio_industry"}],"wp:post_type":[{"href":"https:\/\/designjeem.com\/fr\/wp-json\/wp\/v2\/portfolio?portfolio_industry=70"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}